{"id":520,"date":"2017-07-24T17:02:02","date_gmt":"2017-07-24T21:02:02","guid":{"rendered":"https:\/\/www.joannhoffman.com\/blog\/?p=520"},"modified":"2018-06-08T16:13:49","modified_gmt":"2018-06-08T20:13:49","slug":"dba-informacion-sobre-la-veracidad-en-su-caso","status":"publish","type":"post","link":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/","title":{"rendered":"DBA Informacion sobre la veracidad en su caso"},"content":{"rendered":"<p>Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa de\u00a0su\u00a0lesion\u00a0en\u00a0el\u00a0extranjero\u00a0puede\u00a0recuperar\u00a0el 100% de\u00a0su\u00a0tratamiento\u00a0medico. La\u00a0Seccion\u00a020a le da\u00a0una\u00a0presuncion de\u00a0compensabilidad\u00a0sobre\u00a0las\u00a0causas\u00a0cuando\u00a0usted\u00a0establece\u00a0que\u00a0usted\u00a0fue\u00a0lesionado\u00a0y la lesion\u00a0ocurrio\u00a0en\u00a0el\u00a0extranjero.\u00a0Y\u00a0ciertamente si\u00a0usted\u00a0es\u00a0honesto, \u00a0recibir\u00e1\u00a0probablemente\u00a0los beneficios\u00a0medicos los salarios que se han perdido por\u00a0un\u00a0periodo\u00a0de tiempo.<\/p>\n<p>\nLlegara\u00a0un\u00a0momento\u00a0en\u00a0que la\u00a0compania\u00a0de\u00a0seguros\u00a0llevara\u00a0a\u00a0cabo\u00a0una\u00a0encuesta\u00a0de\u00a0mercado\u00a0de\u00a0trabajo\u00a0para\u00a0mostrarle\u00a0que hay\u00a0puestos\u00a0de\u00a0trabajo\u00a0disponibles\u00a0que\u00a0usted\u00a0puede\u00a0desempenar.\u00a0Cuando\u00a0se\u00a0reune\u00a0con el\u00a0representante\u00a0de la\u00a0compania\u00a0de\u00a0seguros que\u00a0lleva\u00a0a\u00a0cabo\u00a0la\u00a0encuesta\u00a0de\u00a0mercado\u00a0de\u00a0trabajo,\u00a0por\u00a0favor,\u00a0entienda\u00a0que\u00a0debe\u00a0ser\u00a0totalmente honesto\u00a0acerca\u00a0de la informacion\u00a0sobre\u00a0sus\u00a0trabajos\u00a0anteriores,\u00a0incluso revelando\u00a0cuando\u00a0se le\u00a0despidio.\u00a0Tambien\u00a0debe\u00a0responder con\u00a0sinceridad\u00a0si tiene\u00a0alguna\u00a0condena de\u00a0delito\u00a0grave\u00a0(arrestos).\u00a0Los\u00a0abogados de la\u00a0compania\u00a0de\u00a0seguros recolectara\u00a0sus\u00a0registros\u00a0de\u00a0empleos anteriores,\u00a0registros\u00a0medicos y\u00a0antecedentes\u00a0penales.\u00a0Si\u00a0usted\u00a0ha\u00a0mentido\u00a0a la persona de la\u00a0encuesta\u00a0de\u00a0mercado\u00a0de\u00a0trabajo, el\u00a0abogado\u00a0de la\u00a0defensa\u00a0o al medico de la\u00a0compania\u00a0de\u00a0seguros,\u00a0estas\u00a0declaraciones\u00a0falsas son\u00a0una\u00a0razon\u00a0importante para que el juez niegue su\u00a0reclamo.\u00a0Nadie\u00a0espera\u00a0que sea perfecto,\u00a0pero\u00a0si\u00a0honesto.\u00a0Yo\u00a0pienso\u00a0que\u00a0este\u00a0mundo\u00a0seria\u00a0muy aburrido\u00a0si\u00a0todos\u00a0fueramos\u00a0perfectos.\n<\/p>\n<p>\nLa\u00a0misma\u00a0regla\u00a0en\u00a0cuanto\u00a0a la\u00a0honestidad, se\u00a0aplica\u00a0tambien\u00a0con\u00a0su historial\u00a0medico.\u00a0Si\u00a0tuviste dolor o heridas\u00a0en\u00a0la parte\u00a0lesionada\u00a0de\u00a0tu\u00a0cuerpo\u00a0en\u00a0el\u00a0pasado,\u00a0debe ser\u00a0sincero\u00a0y\u00a0debe revelarlo.\u00a0Si\u00a0no\u00a0recuerdas\u00a0una\u00a0lesion\u00a0anterior o\u00a0un\u00a0dolor\u00a0previo,\u00a0es\u00a0mejor\u00a0decir\u00a0&#8220;no lo\u00a0recuerdo.&#8221; No hay\u00a0necesidad\u00a0de\u00a0salir con una\u00a0extremidad\u00a0y\u00a0decir\u00a0&#8220;No,\u00a0nunca\u00a0me\u00a0lastime\u00a0la\u00a0espalda,\u00a0o\u00a0el\u00a0cuello, etc.&#8221; ya\u00a0\u00a0que \u00a0en\u00a0algun\u00a0lugar\u00a0de\u00a0su\u00a0historial\u00a0medico\u00a0pasado\u00a0\u200b\u200besta registrado dicho dolor o lesion\u00a0previa. Si usted no recuerda esas\u00a0lesiones,\u00a0pero aun\u00a0as\u00ed\u00a0da la impresi\u00f3n erronea de que\u00a0ha mentido, el\u00a0juez\u00a0tomara\u00a0eso como una raz\u00f3n para negar tu reclamo.\n<\/p>\n<p> <a href=\"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/#more-520\" class=\"more-link\">Continue reading \u2192<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa de\u00a0su\u00a0lesion\u00a0en\u00a0el\u00a0extranjero\u00a0puede\u00a0recuperar\u00a0el 100% de\u00a0su\u00a0tratamiento\u00a0medico. La\u00a0Seccion\u00a020a le da\u00a0una\u00a0presuncion de\u00a0compensabilidad\u00a0sobre\u00a0las\u00a0causas\u00a0cuando\u00a0usted\u00a0establece\u00a0que\u00a0usted\u00a0fue\u00a0lesionado\u00a0y la lesion\u00a0ocurrio\u00a0en\u00a0el\u00a0extranjero.\u00a0Y\u00a0ciertamente si\u00a0usted\u00a0es\u00a0honesto, \u00a0recibir\u00e1\u00a0probablemente\u00a0los beneficios\u00a0medicos los salarios que se han perdido por\u00a0un\u00a0periodo\u00a0de tiempo. Llegara\u00a0un\u00a0momento\u00a0en\u00a0que la\u00a0compania\u00a0de\u00a0seguros\u00a0llevara\u00a0a\u00a0cabo\u00a0una\u00a0encuesta\u00a0de\u00a0mercado\u00a0de\u00a0trabajo\u00a0para\u00a0mostrarle\u00a0que hay\u00a0puestos\u00a0de\u00a0trabajo\u00a0disponibles\u00a0que\u00a0usted\u00a0puede\u00a0desempenar.\u00a0Cuando\u00a0se\u00a0reune\u00a0con el\u00a0representante\u00a0de la\u00a0compania\u00a0de\u00a0seguros que\u00a0lleva\u00a0a\u00a0cabo\u00a0la\u00a0encuesta\u00a0de\u00a0mercado\u00a0de\u00a0trabajo,\u00a0por\u00a0favor,\u00a0entienda\u00a0que\u00a0debe\u00a0ser\u00a0totalmente honesto\u00a0acerca\u00a0de la informacion\u00a0sobre\u00a0sus\u00a0trabajos\u00a0anteriores,\u00a0incluso revelando\u00a0cuando\u00a0se le\u00a0despidio.\u00a0Tambien\u00a0debe\u00a0responder con\u00a0sinceridad\u00a0si tiene\u00a0alguna\u00a0condena de\u00a0delito\u00a0grave\u00a0(arrestos).\u00a0Los\u00a0abogados de la\u00a0compania\u00a0de\u00a0seguros recolectara\u00a0sus\u00a0registros\u00a0de\u00a0empleos anteriores,\u00a0registros\u00a0medicos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-520","post","type-post","status-publish","format-standard","hentry","category-longshore-and-dba-claims"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DBA Informacion sobre la veracidad en su caso &#8212; Florida Injury Attorneys Blog &#8212; July 24, 2017<\/title>\n<meta name=\"description\" content=\"Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa &#8212; July 24, 2017\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"DBA Informacion sobre la veracidad en su caso &#8212; Florida Injury Attorneys Blog &#8212; July 24, 2017\" \/>\n<meta name=\"twitter:description\" content=\"Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa &#8212; July 24, 2017\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo Ann Hoffman &amp; Associates, P.A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DBA Informacion sobre la veracidad en su caso &#8212; Florida Injury Attorneys Blog &#8212; July 24, 2017","description":"Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa &#8212; July 24, 2017","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/","twitter_card":"summary_large_image","twitter_title":"DBA Informacion sobre la veracidad en su caso &#8212; Florida Injury Attorneys Blog &#8212; July 24, 2017","twitter_description":"Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa &#8212; July 24, 2017","twitter_misc":{"Written by":"Jo Ann Hoffman &amp; Associates, P.A.","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/#article","isPartOf":{"@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/"},"author":{"name":"Jo Ann Hoffman &amp; Associates, P.A.","@id":"https:\/\/www.joannhoffman.com\/blog\/#\/schema\/person\/18c7150f3eef0adc9ff3ee4e602d2d75"},"headline":"DBA Informacion sobre la veracidad en su caso","datePublished":"2017-07-24T21:02:02+00:00","dateModified":"2018-06-08T20:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/"},"wordCount":459,"articleSection":["Longshore and DBA claims"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/","url":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/","name":"DBA Informacion sobre la veracidad en su caso &#8212; Florida Injury Attorneys Blog &#8212; July 24, 2017","isPartOf":{"@id":"https:\/\/www.joannhoffman.com\/blog\/#website"},"datePublished":"2017-07-24T21:02:02+00:00","dateModified":"2018-06-08T20:13:49+00:00","author":{"@id":"https:\/\/www.joannhoffman.com\/blog\/#\/schema\/person\/18c7150f3eef0adc9ff3ee4e602d2d75"},"description":"Ganar un caso de DBA es f\u00e1cil, cuando se lo hace honestamente. Una\u00a0vez\u00a0que\u00a0usted\u00a0muestre\u00a0el 1% de la causa &#8212; July 24, 2017","breadcrumb":{"@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.joannhoffman.com\/blog\/dba-informacion-sobre-la-veracidad-en-su-caso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joannhoffman.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DBA Informacion sobre la veracidad en su caso"}]},{"@type":"WebSite","@id":"https:\/\/www.joannhoffman.com\/blog\/#website","url":"https:\/\/www.joannhoffman.com\/blog\/","name":"Florida Injury Attorneys Blog","description":"Published by Florida Personal Injury Lawyers \u2014 Jo Ann Hoffman &amp; Associates, P.A.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joannhoffman.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.joannhoffman.com\/blog\/#\/schema\/person\/18c7150f3eef0adc9ff3ee4e602d2d75","name":"Jo Ann Hoffman &amp; Associates, P.A.","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/490f7ea1e6dde3352eb826fe3566ff83f5de365e8ead16e8853c9da0483ad40e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/490f7ea1e6dde3352eb826fe3566ff83f5de365e8ead16e8853c9da0483ad40e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/490f7ea1e6dde3352eb826fe3566ff83f5de365e8ead16e8853c9da0483ad40e?s=96&d=mm&r=g","caption":"Jo Ann Hoffman &amp; Associates, P.A."}}]}},"yoast":{"focuskw":"","title":"","metadesc":"","linkdex":"","metakeywords":"","meta-robots-noindex":"","meta-robots-nofollow":"","meta-robots-adv":"","canonical":"","redirect":"","opengraph-title":"","opengraph-description":"","opengraph-image":"","twitter-title":"","twitter-description":"","twitter-image":""},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":6,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"predecessor-version":[{"id":581,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/posts\/520\/revisions\/581"}],"wp:attachment":[{"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joannhoffman.com\/blog\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}